{"id":415,"date":"2008-06-24T19:54:47","date_gmt":"2008-06-24T18:54:47","guid":{"rendered":"http:\/\/blog.blinkenarea.org\/index.php\/2008\/06\/24\/berlin-im-licht\/"},"modified":"2012-05-25T08:25:20","modified_gmt":"2012-05-25T07:25:20","slug":"berlin-im-licht","status":"publish","type":"post","link":"https:\/\/blog.blinkenarea.org\/index.php\/2008\/06\/24\/berlin-im-licht\/","title":{"rendered":"Berlin im Licht"},"content":{"rendered":"<p>Der regierende B\u00fcrgermeister und Kultursenator von Berlin <a href=\"http:\/\/www.klaus-wowereit.de\/\" title=\"Klaus Wowereit :: Webseite\">Klaus Wowereit<\/a> er\u00f6ffnete gestern Abend eine Sonderausstellung der <a href=\"http:\/\/www.stadtmuseum.de\/index.php\" title=\"Stiftung Stadtmuseum Berlin\">Stiftung Stadmuseum Berlin<\/a> mit dem Titel &#8220;Berlin im Licht&#8221;. Sie wurde anl\u00e4sslich des 100. Geburtstages des <a href=\"http:\/\/de.wikipedia.org\/wiki\/M%C3%A4rkisches_Museum_(Berlin)\" title=\"Wikipedia :: M\u00e4rkisches Museum\">M\u00e4rkischen Museums<\/a> konzipiert und zeigt die wechselnde Bedeutung des Lichts seit der vorletzten Jahrhundertwende.  Der Streifzug durch die Geschichte f\u00fchrt unter anderem vorbei an erster Stra?enbeleuchtung und Leuchtreklame, der Auseinandersetzung \u00fcber Gas oder Elektrizit\u00e4t, der Teilung Berlins bis hin zu modernen Lichtinstallationen und neuer Architektur im Zusammenspiel mit Licht.<\/p>\n<p><a href=\"http:\/\/blog.blinkenarea.org\/wp-content\/uploads\/2008\/06\/berlinimlicht.jpg\" rel=\"lightbox\"><\/a><\/p>\n<p style=\"text-align: center\"><a href=\"http:\/\/blog.blinkenarea.org\/wp-content\/uploads\/2008\/06\/berlinimlicht.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.blinkenarea.org\/wp-content\/uploads\/2008\/06\/.thumbs\/.berlinimlicht.jpg\" alt=\"Berlin im Licht\" title=\"Berlin im Licht\" border=\"0\" height=\"190\" hspace=\"5\" vspace=\"5\" width=\"200\" \/><\/a><\/p>\n<p>Ein Teil dieser Ausstellung ist <a href=\"https:\/\/wiki.blinkenarea.org\/index.php\/LittleLights\" title=\"LittleLights :: BlinkenArea Wiki\">LittleLights<\/a> &#8211; Stadtinszenierung der Gegenwart. Noch bis zum 1. Februar 2009 k\u00f6nnen die Besucher es in einem Raum mit dem Thema &#8220;Clubszene&#8221; bewundern.<\/p>\n<ul>\n<li><a href=\"http:\/\/www.stadtmuseum.de\/berlinimlicht\/\" title=\"Webseite Berlin im Licht\">Webseite<\/a><\/li>\n<li><a href=\"http:\/\/www.stadtmuseum.de\/berlinimlicht\/bilder\/Programm1213343238_pdf_.pdf\" title=\"Programm :: Berlin im Licht\">Programm (.pdf)<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Der regierende B\u00fcrgermeister und Kultursenator von Berlin Klaus Wowereit er\u00f6ffnete gestern Abend eine Sonderausstellung der Stiftung Stadmuseum Berlin mit dem Titel &#8220;Berlin im Licht&#8221;. Sie wurde anl\u00e4sslich des 100. Geburtstages des M\u00e4rkischen Museums konzipiert und zeigt die wechselnde Bedeutung des<span class=\"ellipsis\">&hellip;<\/span><\/p>\n<div class=\"read-more\"><a href=\"https:\/\/blog.blinkenarea.org\/index.php\/2008\/06\/24\/berlin-im-licht\/\">Read more <span class=\"screen-reader-text\">Berlin im Licht<\/span><span class=\"meta-nav\"> &#8250;<\/span><\/a><\/div>\n<p><!-- end of .read-more --><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,14,2,12],"tags":[407],"class_list":["post-415","post","type-post","status-publish","format-standard","hentry","category-blink","category-events","category-german","category-littlelights","tag-littlelights"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2kRSv-6H","_links":{"self":[{"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/posts\/415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/comments?post=415"}],"version-history":[{"count":1,"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/posts\/415\/revisions"}],"predecessor-version":[{"id":1427,"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/posts\/415\/revisions\/1427"}],"wp:attachment":[{"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/media?parent=415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/categories?post=415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.blinkenarea.org\/index.php\/wp-json\/wp\/v2\/tags?post=415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}